{"id":8121,"date":"2023-03-02T16:54:37","date_gmt":"2023-03-02T21:54:37","guid":{"rendered":"http:\/\/wp.uaslp.mx\/noticias\/?p=8121"},"modified":"2023-05-08T12:46:08","modified_gmt":"2023-05-08T17:46:08","slug":"del-17-al-19-de-mayo-de-2023-se-realizara-el-2o-foro-estatal-del-agua-en-la-fepzh","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/comunidad\/del-17-al-19-de-mayo-de-2023-se-realizara-el-2o-foro-estatal-del-agua-en-la-fepzh\/","title":{"rendered":"Del 17 al 19 de mayo de 2023, se realizar\u00e1 el 2\u00ba Foro Estatal del Agua en la FEPZH"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con la finalidad de abordar temas que puedan coadyuvar a la problem\u00e1tica del agua, la Universidad Aut\u00f3noma de San Luis a trav\u00e9s de la<a href=\"https:\/\/www.facebook.com\/uaslp.fcq\/?locale=es_LA\" target=\"_blank\" rel=\"noopener\" title=\"\"> Facultad de Ciencias Qu\u00edmicas<\/a> y la <a href=\"https:\/\/es-la.facebook.com\/uaslp.zona.huasteca\/\" title=\"\">Facultad de Estudios Profesionales Zona Huasteca<\/a>, llevar\u00e1n a cabo el 2\u00ba. Foro Estatal del Agua; el evento tendr\u00e1 como sede las instalaciones de la FEPZH en Ciudad Valles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doctora Alma Gabriela Palestino Escobedo, directora de la Facultad de Ciencias Qu\u00edmicas, explic\u00f3 que este evento se realiza como continuidad del primer foro que se realiz\u00f3 el a\u00f1o pasado. \u201cEn esa ocasi\u00f3n se tuvo la presentaci\u00f3n de problem\u00e1ticas locales de la zona metropolitana, principalmente, al cual acudieron alrededor de 250 personas, que discutieron y sugirieron soluciones para la problem\u00e1tica que tenemos en materia de agua en el Estado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que para dar seguimiento a los compromisos que se adquirieron, se decidi\u00f3 mover el foro a la Huasteca, \u201cpara darle mayor oportunidad a nuestros compa\u00f1eros y colegas de esa zona del Estado, para que puedan participar y llevarles un evento m\u00e1s cercano a las problem\u00e1ticas locales\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera, la doctora Gabriela Palestino destac\u00f3 la importancia de este Foro, \u201cel agua es una necesidad, es un derecho humano; sin embargo, tambi\u00e9n tenemos como beneficiarios y como consumidores, establecer estrategias para no agotar este recurso y poderlo reutilizar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que eso son algunos de los objetivos de las reuniones, \u201cy que tanto la poblaci\u00f3n como los sectores acad\u00e9mico y empresarial, podamos reunirnos para revisar las problem\u00e1ticas y tratar de encontrar soluciones vitales que se puedan implementar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 tambi\u00e9n que en este 2\u00ba. Foro Estatal del Agua tambi\u00e9n participa el Consejo Potosino de Ciencia y Tecnolog\u00eda (COPOCYT), adem\u00e1s de que se espera la incorporaci\u00f3n de autoridades municipales de Ciudad Valles, interesados en este segundo foro, como lo es la Comisi\u00f3n del Agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre las tem\u00e1ticas a abordar en este importante evento destacan: Agua y Cambio Clim\u00e1tico, Estado de los Recursos Acu\u00e1ticos Superficiales, Agua y Desarrollo, El Derecho Humano al Agua, los Derechos de la Naturaleza, Cultura del Agua, Salud y Tratamiento del Agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la doctora Gabriela Palestino Escobedo hace una atenta invitaci\u00f3n a estudiantes, investigadoras e investigadores y sociedad en general para que participen, el evento tiene un costo de recuperaci\u00f3n y se requiere un registro previo, mismo que puede realizarse v\u00eda Google Forms, que se encuentra en las p\u00e1ginas de las redes sociales de las entidades organizadoras. Para mayores informes al correo electr\u00f3nico <a href=\"mailto:foroagua@cq.uaslp.mx\" title=\"\">foroagua@cq.uaslp.mx<\/a>.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Am\u00e9rica Reyes\/MR<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/05\/ALMA-GABRIELA-PALESTINO-ESCOBEDO-UASL8321-opt.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"8995\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/05\/ALMA-GABRIELA-PALESTINO-ESCOBEDO-UASL8321-opt.jpg\" alt=\"\" class=\"wp-image-8995\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/05\/ALMA-GABRIELA-PALESTINO-ESCOBEDO-UASL8321-opt.jpg 1600w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/05\/ALMA-GABRIELA-PALESTINO-ESCOBEDO-UASL8321-opt-1024x768.jpg 1024w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/05\/ALMA-GABRIELA-PALESTINO-ESCOBEDO-UASL8321-opt-768x576.jpg 768w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/05\/ALMA-GABRIELA-PALESTINO-ESCOBEDO-UASL8321-opt-1536x1152.jpg 1536w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/05\/ALMA-GABRIELA-PALESTINO-ESCOBEDO-UASL8321-opt-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de abordar temas que puedan coadyuvar a la problem\u00e1tica del agua, la&#8230;<\/p>\n","protected":false},"author":12,"featured_media":8122,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"{\"enableLightbox\":true,\"useGlobalPreset\":true,\"nativGalleryEnable\":true,\"nativeAttachment\":true,\"singletonAttachment\":true,\"groupingAllImages\":false,\"lightboxType\":\"classic\",\"copyRProtection\":false,\"copyRAlert\":\"Hello, this photo is mine!\",\"sliderScrollNavi\":false,\"sliderNextPrevAnimation\":\"animation\",\"galleryScrollPositionControll\":false,\"sliderVideoAutoPlay\":false,\"sliderTryPlayNext\":false,\"sliderVideoLoop\":false,\"sliderItemCounterEnable\":true,\"sliderItemTitleEnable\":false,\"sliderItemTitleFontSize\":18,\"sliderItemTitleTextColor\":\"rgba(255,255,255,1)\",\"itemCounterColor\":\"rgba(255,255,255,1)\",\"sliderThumbBarEnable\":true,\"sliderThumbBarHoverColor\":\"rgba(240,240,240,1)\",\"sliderBgColor\":\"rgba(0,0,0,0.8)\",\"sliderPreloaderColor\":\"rgba(240,240,240,1)\",\"sliderHeaderFooterBgColor\":\"rgba(0,0,0,0.4)\",\"sliderNavigationColor\":\"rgba(0,0,0,1)\",\"sliderNavigationColorOver\":\"rgba(255,255,255,1)\",\"sliderNavigationIconColor\":\"rgba(255,255,255,1)\",\"sliderNavigationIconColorOver\":\"rgba(0,0,0,1)\",\"sliderSlideshow\":true,\"sliderSlideshowDelay\":8,\"slideshowIndicatorColor\":\"rgba(255,255,255,1)\",\"slideshowIndicatorColorBg\":\"rgba(255,255,255,0.5)\",\"sliderThumbSubMenuBackgroundColor\":\"rgba(255,255,255,0)\",\"sliderThumbSubMenuBackgroundColorOver\":\"rgba(255,255,255,1)\",\"sliderThumbSubMenuIconColor\":\"rgba(255,255,255,1)\",\"sliderThumbSubMenuIconHoverColor\":\"rgba(0,0,0,1)\",\"sliderSocialShareEnabled\":true,\"sliderZoomEnable\":true,\"sliderFullscreenEnabled\":true,\"modaBgColor\":\"rgba(0,0,0,0.8)\",\"modalIconColor\":\"rgba(255,255,255,1)\",\"modalIconColorHover\":\"rgba(255,255,255,0.8)\",\"shareFacebook\":true,\"shareTwitter\":true,\"sharePinterest\":true,\"sliderItemDownload\":true,\"shareCopyLink\":true}","footnotes":""},"categories":[5],"tags":[30,332,348,584],"class_list":["post-8121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","tag-agua","tag-fepzh","tag-foro","tag-quimica"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2.jpg",1077,937,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2-150x150.jpg",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2-1024x891.jpg",1024,891,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2-768x668.jpg",640,557,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2.jpg",1077,937,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2.jpg",1077,937,false],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2.jpg",1077,937,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2-1077x845.jpg",1077,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2-1024x891.jpg",1024,891,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2-720x475.jpg",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/03\/foro2.jpg",1077,937,false]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/giovannamorales\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/comunidad\/\" rel=\"category tag\">Comunidad<\/a>","tag_info":"Comunidad","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/8121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=8121"}],"version-history":[{"count":3,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/8121\/revisions"}],"predecessor-version":[{"id":8996,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/8121\/revisions\/8996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/8122"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=8121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=8121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=8121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}