{"id":6737,"date":"2022-11-24T18:20:25","date_gmt":"2022-11-24T23:20:25","guid":{"rendered":"http:\/\/wp.uaslp.mx\/noticias\/?p=6737"},"modified":"2022-11-25T11:38:10","modified_gmt":"2022-11-25T16:38:10","slug":"signan-uaslp-y-unasam-de-peru-convenio-de-colaboracion","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/academica\/signan-uaslp-y-unasam-de-peru-convenio-de-colaboracion\/","title":{"rendered":"Signan UASLP y UNASAM de Per\u00fa convenio de colaboraci\u00f3n\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Como parte de la visi\u00f3n multicultural que fomenta la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP), se realiz\u00f3 la firma de colaboraci\u00f3n entre la casa de estudios potosina y la Universidad Nacional Santiago Ant\u00fanez de Mayolo (UNASAM) de Per\u00fa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue en el Edificio Central donde se sign\u00f3 el convenio con el fin de aunar esfuerzos para llevar a cabo acciones conjuntas en temas de inter\u00e9s rec\u00edproco en las \u00e1reas de investigaci\u00f3n, extensi\u00f3n, cultura, asistencia t\u00e9cnica, administrativa y acad\u00e9mica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se generar\u00e1 una experiencia de acercamiento que permita estrechar los lazos interinstitucionales al inicio de esta primera etapa de colaboraci\u00f3n, mismos que inician con la llegada de 24 estudiantes peruanos, de los cuales 20 estar\u00e1n en la carrera de Arquitectura y Urbanismo y cuatro en Ingenier\u00eda Civil.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje, el doctor Alejandro Javier Zerme\u00f1o Guerra, rector de la UASLP, consider\u00f3 que este tipo de convenios de colaboraci\u00f3n van a ser de gran beneficio para ambas instituciones, adem\u00e1s, abonan a la visi\u00f3n de interculturalidad que mantiene la universidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el doctor Marco Silva Lindo, vicerrector acad\u00e9mico de la UNASAM, se\u00f1al\u00f3 que con este convenio se realizan m\u00e1s v\u00ednculos y seguramente en un futuro cercano, se podr\u00e1n hacer pasant\u00edas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento estuvieron presentes, por parte de la UASLP, el maestro Jorge Alberto P\u00e9rez Gonz\u00e1lez, secretario acad\u00e9mico; la maestra Idalia Acosta Castillo, directora de Internacionalizaci\u00f3n; la maestra Rosa Mar\u00eda Reyes Guerrero, directora de la Facultad del H\u00e1bitat; el doctor Emilio Gonz\u00e1lez, director de la Facultad de Ingenier\u00eda y el maestro Daniel Jim\u00e9nez, integrante de la coordinaci\u00f3n de la visita.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por parte de la UNASAM, estuvieron presentes el doctor Marco Silva Lindo, vicerrector acad\u00e9mico; el doctor Reynaldo Reyes Roque, director de la Escuela Profesional de Ingenier\u00eda Civil; el maestro Gustavo de la Cruz due\u00f1as, director de la Escuela Profesional de Arquitectura y Urbanismo y la maestra Beatriz del Castillo, docente de la UNASAM.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Hugo Lauss\u00edn\/TC<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1200\" data-id=\"6758\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-1-1.jpg\" alt=\"\" class=\"wp-image-6758\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-1-1.jpg 1800w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-1-1-1024x683.jpg 1024w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-1-1-768x512.jpg 768w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-1-1-1536x1024.jpg 1536w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-1-1-1320x880.jpg 1320w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de la visi\u00f3n multicultural que fomenta la Universidad Aut\u00f3noma de San Luis Potos\u00ed&#8230;<\/p>\n","protected":false},"author":12,"featured_media":6750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[2],"tags":[195,1201],"class_list":["post-6737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academica","tag-convenio","tag-unasam"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1.jpg",1800,1200,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1-150x150.jpg",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1-1024x683.jpg",1024,683,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1-768x512.jpg",640,427,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1.jpg",1800,1200,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1.jpg",1800,1200,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1-1280x845.jpg",1280,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1-1024x683.jpg",1024,683,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1-720x475.jpg",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/11\/24nov-2-1-1320x880.jpg",1320,880,true]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/giovannamorales\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/academica\/\" rel=\"category tag\">Acad\u00e9mica<\/a>","tag_info":"Acad\u00e9mica","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/6737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=6737"}],"version-history":[{"count":4,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/6737\/revisions"}],"predecessor-version":[{"id":6759,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/6737\/revisions\/6759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/6750"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=6737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=6737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=6737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}