{"id":2753,"date":"2022-02-24T13:23:00","date_gmt":"2022-02-24T18:23:00","guid":{"rendered":"https:\/\/www.noticiasuaslp.com\/?p=2753"},"modified":"2022-10-19T13:46:13","modified_gmt":"2022-10-19T18:46:13","slug":"mas-de-60-investigadoras-e-investigadores-participaron-en-el-primer-foro-transformakers","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/investigacion\/mas-de-60-investigadoras-e-investigadores-participaron-en-el-primer-foro-transformakers\/","title":{"rendered":"M\u00e1s de 60 investigadoras e investigadores participaron en el Primer Foro Transformakers"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Para promover espacios de convergencia de intereses y difusi\u00f3n de la investigaci\u00f3n que se realiza en la Universidad Aut\u00f3noma de San Luis Potos\u00ed, as\u00ed como fomentar la interdisciplinariedad, la innovaci\u00f3n y el trabajo colaborativo, la <a rel=\"noreferrer noopener\" href=\"http:\/\/www.uaslp.mx\/InvestigacionyPosgrado\" target=\"_blank\">Secretar\u00eda de Investigaci\u00f3n y Posgrado (SIP)<\/a> llev\u00f3 a cabo el <em><a href=\"http:\/\/www.uaslp.mx\/InvestigacionyPosgrado\/Paginas\/TransforMaker-2021\/TransforMaker-2021.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">1\u00ba Foro TransforMakers: Creando v\u00ednculos para la generaci\u00f3n de recursos para investigaci\u00f3n y desarrollo<\/a><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento, realizado el pasado el mi\u00e9rcoles 23 de febrero de 2022, se convirti\u00f3 en un punto de encuentro virtual entre m\u00e1s de 60 investigadoras e investigadores adscritos a los campus fuera de la capital potosina, as\u00ed como de <a rel=\"noreferrer noopener\" href=\"https:\/\/conacyt.mx\/conacyt\/areas-del-conacyt\/desarrollo-cientifico\/catedras-conacyt\/\" target=\"_blank\">C\u00e1tedra Conacyt<\/a> de esta casa de estudios. Se desarroll\u00f3, a trav\u00e9s de una plataforma especializada que permiti\u00f3 a los participantes interactuar en tiempo real y hacer <em><a href=\"https:\/\/www.ceupe.mx\/blog\/que-es-el-networking.html#:~:text=El%20Networking%20es%20una%20pr%C3%A1ctica,naturales%20que%20hagan%20parte%20de\" target=\"_blank\" rel=\"noreferrer noopener\">networking<\/a><\/em> por medio de avatares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La conferencia magistral estuvo a cargo de la Dra. Rosalba Medina Rivera, directora general del <a href=\"https:\/\/slp.gob.mx\/copocyt\/Paginas\/Inicio.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Consejo Potosino de Ciencia y Tecnolog\u00eda (Copocyt)<\/a>, quien present\u00f3 diversos modelos de vinculaci\u00f3n con actores externos y estrategias para aumentar el imparto de la investigaci\u00f3n que se realiza en la regi\u00f3n potosina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el foro, las y los participantes tuvieron la oportunidad de presentar sus proyectos de investigaci\u00f3n, a trav\u00e9s de videos, organizados de acuerdo a los <a rel=\"noreferrer noopener\" href=\"https:\/\/conacyt.mx\/pronaces\/\" target=\"_blank\">Programas Nacionales Estrat\u00e9gicos del Conacyt (PRONACES)<\/a> y los <a rel=\"noreferrer noopener\" href=\"https:\/\/www.un.org\/sustainabledevelopment\/es\/objetivos-de-desarrollo-sostenible\/\" target=\"_blank\">Objetivos de Desarrollo Sostenible (ODS) de la Agenda 2030<\/a>, en seis aldeas distintas: Salud; Cultura, Creatividad y Sociedad Inclusiva; Seguridad Humana y Educaci\u00f3n; Tecnolog\u00eda, Industria y Espacio; Medio Ambiente, Energ\u00eda y Movilidad; y Recursos Naturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento fue presidido por el Dr. Amaury de Jes\u00fas Pozos Guill\u00e9n, secretario de <a href=\"http:\/\/www.uaslp.mx\/InvestigacionyPosgrado\" target=\"_blank\" rel=\"noreferrer noopener\">Investigaci\u00f3n y Posgrado<\/a>, acompa\u00f1ado por la Dra. Rosalba Medina Rivera, directora del <a href=\"https:\/\/slp.gob.mx\/copocyt\/Paginas\/Inicio.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Copocyt<\/a>, el Mtro. Gylmar Mariel C\u00e1rdenas, jefe de la <a href=\"http:\/\/www.uaslp.mx\/Vinculacion\" target=\"_blank\" rel=\"noreferrer noopener\">Divisi\u00f3n de Vinculaci\u00f3n Universitaria<\/a>, y la Dra. Rosalba Badillo Vega, directora de Gesti\u00f3n del Conocimiento y la Innovaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se cont\u00f3 con la presencia del Dr. Isaac Compe\u00e1n Mart\u00ednez, director de la Coordinaci\u00f3n Acad\u00e9mica Regi\u00f3n Altiplano; Dr. Jorge Alonso Alcal\u00e1 J\u00e1uregui, director de la Coordinaci\u00f3n Acad\u00e9mica Regi\u00f3n Altiplano Oeste; Mtro. \u00d3scar Fern\u00e1ndez P\u00e9rez-Tejada, director de la Coordinaci\u00f3n Acad\u00e9mica Regi\u00f3n Huasteca Sur; Dr. Roel Cruz Gaona, director del Instituto de Metalurgia; Dra. Alma Gabriela Palestino Escobedo, directora de la Facultad de Ciencias Qu\u00edmicas; Dr. Ricardo Alberto Guirado L\u00f3pez, director del Instituto de F\u00edsica; Dr. Roel Cruz Gaona, Instituto de Metalurgia; Dr. Daniel Ulises Campos Delgado, director del Instituto de Investigaci\u00f3n en Comunicaci\u00f3n \u00d3ptica y del Dr. Rub\u00e9n Alfonso L\u00f3pez Doncel, Director del Instituto de Geolog\u00eda como invitados especiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para promover espacios de convergencia de intereses y difusi\u00f3n de la investigaci\u00f3n que se realiza&#8230;<\/p>\n","protected":false},"author":12,"featured_media":2752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[10],"tags":[348,659,694],"class_list":["post-2753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investigacion","tag-foro","tag-sip","tag-transformakers"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers.jpg",1600,1200,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-150x150.jpg",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-300x225.jpg",300,225,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-768x576.jpg",640,480,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-1536x1152.jpg",1536,1152,true],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers.jpg",1600,1200,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-1280x845.jpg",1280,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-1024x768.jpg",1024,768,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-720x475.jpg",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2022\/04\/Foro-Transformakers-1320x990.jpg",1320,990,true]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/giovannamorales\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/investigacion\/\" rel=\"category tag\">Investigaci\u00f3n<\/a>","tag_info":"Investigaci\u00f3n","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/2753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=2753"}],"version-history":[{"count":1,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/2753\/revisions"}],"predecessor-version":[{"id":6062,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/2753\/revisions\/6062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/2752"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=2753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=2753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=2753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}