{"id":26072,"date":"2026-07-14T12:11:48","date_gmt":"2026-07-14T18:11:48","guid":{"rendered":"https:\/\/wp.uaslp.mx\/noticias\/?p=26072"},"modified":"2026-07-14T12:27:31","modified_gmt":"2026-07-14T18:27:31","slug":"fen-convoca-a-su-comunidad-a-construir-la-memoria-de-sus-primeros-30-anos-como-facultad","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/academica\/fen-convoca-a-su-comunidad-a-construir-la-memoria-de-sus-primeros-30-anos-como-facultad\/","title":{"rendered":"FEN  convoca a su comunidad a construir la memoria de sus primeros 30 a\u00f1os como facultad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con motivo del 30 aniversario de la creaci\u00f3n de la <a href=\"https:\/\/www.enfermerianutricion.uaslp.mx\/\">Facultad de Enfermer\u00eda y Nutrici\u00f3n<\/a> (FEN) de la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP), la instituci\u00f3n inici\u00f3 la construcci\u00f3n de un acervo conmemorativo que reunir\u00e1 fotograf\u00edas, documentos, uniformes, insignias, material cl\u00ednico, videos y otros objetos que permitan preservar la historia de las \u00faltimas tres d\u00e9cadas, sin dejar de reconocer los m\u00e1s de 115 a\u00f1os de formaci\u00f3n de profesionales de la salud que anteceden a esta etapa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doctora M\u00f3nica Luc\u00eda Acebo Mart\u00ednez, secretaria de Vinculaci\u00f3n y Extensi\u00f3n de la FEN, explic\u00f3 que la celebraci\u00f3n busca destacar el momento en que la entonces escuela obtuvo el reconocimiento como facultad gracias a la consolidaci\u00f3n de sus programas de posgrado. &#8220;La facultad es centenaria, nosotros tenemos registros en donde hay m\u00e1s de 115 a\u00f1os en la formaci\u00f3n de personal de salud, pero no quisimos dejar pasar esos 30 a\u00f1os en donde ya se da el grado de facultad&#8221;, se\u00f1al\u00f3. Agreg\u00f3 que el aniversario se resume en el lema: &#8220;30 a\u00f1os como facultad, m\u00e1s de 100 a\u00f1os formando profesionales de la salud&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, la Facultad hace un llamado a egresados, docentes y personal que haya formado parte de su historia para que compartan materiales que ayuden a reconstruir la memoria institucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El enfermero Abelardo Rosillo Mendieta, docente y responsable de Servicio Social y Campos de Pr\u00e1ctica, invit\u00f3 a quienes conserven recuerdos de distintas generaciones a sumarse a la iniciativa. &#8220;Si tienen alg\u00fan recuerdo que nos quieran compartir, que nos presten temporalmente, ser\u00e1 bienvenido&#8221;, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los objetos de inter\u00e9s se encuentran antiguos escudos, reconocimientos, uniformes, cofias, capas utilizadas por el personal de enfermer\u00eda, as\u00ed como instrumentos m\u00e9dicos que hoy han quedado en desuso. Rosillo Mendieta coment\u00f3 que incluso art\u00edculos como jeringas de vidrio o materiales utilizados d\u00e9cadas atr\u00e1s permitir\u00e1n mostrar la evoluci\u00f3n de la profesi\u00f3n. &#8220;El adelanto cient\u00edfico ha llegado mucho m\u00e1s all\u00e1, pero es bueno recordarlo para que las nuevas generaciones conozcan de d\u00f3nde venimos&#8221;, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La convocatoria tambi\u00e9n contempla la recuperaci\u00f3n de material audiovisual. La doctora Acebo Mart\u00ednez se\u00f1al\u00f3 que ya han recibido fotograf\u00edas y documentos hist\u00f3ricos, mientras que el docente explic\u00f3 que existen alternativas para digitalizar grabaciones almacenadas en formatos antiguos como VHS o Beta. &#8220;Lo importante es que se cree este acervo y que la historia de la facultad permanezca por mucho m\u00e1s tiempo&#8221;, destac\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los organizadores aclararon que las personas interesadas pueden realizar donaciones o pr\u00e9stamos temporales, ya que la Facultad implementar\u00e1 un procedimiento formal para resguardar cada pieza y devolverla a sus propietarios al concluir la exhibici\u00f3n. &#8220;Si\u00e9ntanse seguros de que el objeto que ustedes han cuidado por tanto tiempo, nosotros lo vamos a cuidar de la misma manera&#8221;, asegur\u00f3 la secretaria de Vinculaci\u00f3n y Extensi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, la recepci\u00f3n de materiales se realiza en la Secretar\u00eda de Vinculaci\u00f3n y Extensi\u00f3n de la Facultad de Enfermer\u00eda y Nutrici\u00f3n, con una fecha tentativa de cierre el 24 de julio, aunque podr\u00eda ampliarse de acuerdo con la respuesta de la comunidad universitaria. Una vez concluida la integraci\u00f3n del acervo, la UASLP dar\u00e1 a conocer la fecha en que ser\u00e1 presentado al p\u00fablico como parte de las actividades conmemorativas del 30 aniversario de la Facultad.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Hugo Laussin<\/em><\/p>\n\n\n<div class=\"pgc-sgb-cb wp-block-pgcsimplygalleryblock-justified \" data-gallery-id=\"56f68261\"><div class=\"sgb-preloader\" id=\"pr_56f68261\">\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div><\/div><div class=\"simply-gallery-amp pgc_sgb_slider \"><noscript><div class=\"sgb-gallery\"><div class=\"sgb-item\"><a href=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.29-AM.jpeg\"><img decoding=\"async\" alt=\"\" width=\"1024\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.29-AM-1024x1024.jpeg\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.29-AM-1024x1024.jpeg 1024w,https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.29-AM.jpeg 1254w\" sizes=\"auto, 250px\"\/><\/a><\/div><\/div><\/noscript><\/div><script type=\"application\/json\" class=\"sgb-data\">{\"galleryType\":\"pgc_sgb_justified\",\"galleryId\":\"56f68261\",\"images\":[{\"id\":26073,\"title\":\"WhatsApp Image 2026-07-14 at 11.58.29 AM\",\"url\":\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.29-AM.jpeg\",\"link\":\"https:\/\/wp.uaslp.mx\/noticias\/academica\/fen-convoca-a-su-comunidad-a-construir-la-memoria-de-sus-primeros-30-anos-como-facultad\/attachment\/whatsapp-image-2026-07-14-at-11-58-29-am\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1254,\"height\":1254,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.29-AM-150x150.jpeg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":1024,\"width\":1024,\"url\":\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.29-AM-1024x1024.jpeg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.29-AM.jpeg\",\"height\":1254,\"width\":1254,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[],\"alt\":\"\"},\"meta\":false}],\"itemsMetaDataCollection\":[]}<\/script><script>(function(){if(window.PGC_SGB && window.PGC_SGB.searcher){window.PGC_SGB.searcher.initBlocks()}})()<\/script><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo del 30 aniversario de la creaci\u00f3n de la Facultad de Enfermer\u00eda y Nutrici\u00f3n&#8230;<\/p>\n","protected":false},"author":12,"featured_media":26074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-26072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academica"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM.jpeg",1600,1200,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM-150x150.jpeg",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM-1024x768.jpeg",1024,768,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM-768x576.jpeg",640,480,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM.jpeg",1600,1200,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM-1536x1152.jpeg",1536,1152,true],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM.jpeg",1600,1200,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM-1280x845.jpeg",1280,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM-1024x768.jpeg",1024,768,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM-720x475.jpeg",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.58.28-AM-1320x990.jpeg",1320,990,true]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/giovannamorales\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/academica\/\" rel=\"category tag\">Acad\u00e9mica<\/a>","tag_info":"Acad\u00e9mica","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/26072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=26072"}],"version-history":[{"count":3,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/26072\/revisions"}],"predecessor-version":[{"id":26082,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/26072\/revisions\/26082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/26074"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=26072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=26072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=26072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}