{"id":24971,"date":"2026-05-13T11:27:39","date_gmt":"2026-05-13T17:27:39","guid":{"rendered":"https:\/\/wp.uaslp.mx\/noticias\/?p=24971"},"modified":"2026-05-13T11:33:21","modified_gmt":"2026-05-13T17:33:21","slug":"egresada-consolida-trayectoria-internacional-en-diseno-desde-canada","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/egresados\/egresada-consolida-trayectoria-internacional-en-diseno-desde-canada\/","title":{"rendered":"Egresada consolida trayectoria internacional en dise\u00f1o desde Canad\u00e1"},"content":{"rendered":"\n<p>La formaci\u00f3n acad\u00e9mica recibida en la <a href=\"https:\/\/habitat.uaslp.mx\/#gsc.tab=0\">Facultad del H\u00e1bitat <\/a>de la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) ha permitido que la egresada Ana Paola Mart\u00ednez Saldierna consolide una exitosa trayectoria profesional en Canad\u00e1, donde actualmente se desempe\u00f1a como l\u00edder de un equipo de dise\u00f1o especializado en color, materiales y acabados para veh\u00edculos recreacionales, destacando por su creatividad e innovaci\u00f3n en proyectos de alcance internacional.<\/p>\n\n\n\n<p>Licenciada en Dise\u00f1o Gr\u00e1fico, generaci\u00f3n 2004-2009, Ana Paola comparti\u00f3 que los conocimientos adquiridos en la UASLP fueron fundamentales para construir las bases que le permitieron explorar distintas ramas del dise\u00f1o y abrirse paso en escenarios profesionales altamente competitivos.<\/p>\n\n\n\n<p>Tras iniciar su trayectoria laboral en San Luis Potos\u00ed en el \u00e1rea de dise\u00f1o editorial, posteriormente incursion\u00f3 en dise\u00f1o aplicado a producto, experiencia que despert\u00f3 su inter\u00e9s por ampliar horizontes profesionales en el extranjero. Despu\u00e9s de enviar su portafolio a diversas empresas internacionales, recibi\u00f3 una oportunidad laboral en Quebec, Canad\u00e1, donde desde hace diez a\u00f1os desarrolla una carrera ascendente.<\/p>\n\n\n\n<p>Actualmente ocupa el cargo de dise\u00f1adora CMF (Color, Materials and Finishes, por sus siglas en ingl\u00e9s), especialidad enfocada en el desarrollo de acabados est\u00e9ticos para veh\u00edculos recreativos. Su desempe\u00f1o y capacidad creativa la llevaron a evolucionar de una posici\u00f3n junior hasta convertirse en l\u00edder de equipo dentro de la empresa.<\/p>\n\n\n\n<p>Mart\u00ednez Saldierna destac\u00f3 que la formaci\u00f3n recibida en la Facultad del H\u00e1bitat fue clave para enfrentar con \u00e9xito nuevos retos profesionales. Se\u00f1al\u00f3 que la universidad le proporcion\u00f3 una visi\u00f3n integral del dise\u00f1o, as\u00ed como herramientas que le permitieron adaptarse a \u00e1reas especializadas que inicialmente desconoc\u00eda.<\/p>\n\n\n\n<p>\u201cSiempre comparto que la Facultad del H\u00e1bitat te brinda bases s\u00f3lidas y generales del dise\u00f1o, pero tambi\u00e9n te impulsa a descubrir nuevas posibilidades. El dise\u00f1o tiene much\u00edsimas ramas, y cada estudiante debe explorar y encontrar su propio camino\u201d, expres\u00f3.<\/p>\n\n\n\n<p>Entre sus logros m\u00e1s destacados record\u00f3 haber sido seleccionada en una bienal de cartel durante su etapa profesional en M\u00e9xico, as\u00ed como el desarrollo reciente de una colecci\u00f3n de motos acu\u00e1ticas en Canad\u00e1, proyecto que super\u00f3 las expectativas de producci\u00f3n de la empresa debido a su aceptaci\u00f3n comercial, reconocimiento que reafirm\u00f3 la importancia estrat\u00e9gica del dise\u00f1o de color en la industria.<\/p>\n\n\n\n<p>Adem\u00e1s de su desarrollo profesional, la egresada ha mantenido v\u00ednculo con su alma mater mediante charlas virtuales dirigidas a estudiantes, en las que comparte su experiencia internacional y orienta a nuevas generaciones sobre las m\u00faltiples posibilidades del dise\u00f1o contempor\u00e1neo.<\/p>\n\n\n\n<p>Ana Paola tambi\u00e9n manifest\u00f3 su inter\u00e9s por continuar la exploraci\u00f3n \u00e1reas como el dise\u00f1o sustentable y el liderazgo creativo, convencida de que la innovaci\u00f3n y la preparaci\u00f3n constante son esenciales para responder a las exigencias de una industria en permanente transformaci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Paola Mu\u00f1oz<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" data-id=\"24974\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.43-AM.jpeg\" alt=\"\" class=\"wp-image-24974\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.43-AM.jpeg 1600w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.43-AM-1024x683.jpeg 1024w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.43-AM-768x512.jpeg 768w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.43-AM-1536x1024.jpeg 1536w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.43-AM-1320x880.jpeg 1320w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" data-id=\"24973\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM-1.jpeg\" alt=\"\" class=\"wp-image-24973\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM-1.jpeg 1600w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM-1-1024x683.jpeg 1024w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM-1-768x512.jpeg 768w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM-1-1536x1024.jpeg 1536w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM-1-1320x880.jpeg 1320w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1147\" data-id=\"24972\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM.jpeg\" alt=\"\" class=\"wp-image-24972\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM.jpeg 1280w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM-1024x918.jpeg 1024w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.42-AM-768x688.jpeg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La formaci\u00f3n acad\u00e9mica recibida en la Facultad del H\u00e1bitat de la Universidad Aut\u00f3noma de San&#8230;<\/p>\n","protected":false},"author":12,"featured_media":24975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[3359],"tags":[],"class_list":["post-24971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-egresados"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM.jpeg",1280,960,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM-150x150.jpeg",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM-1024x768.jpeg",1024,768,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM-768x576.jpeg",640,480,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM.jpeg",1280,960,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM.jpeg",1280,960,false],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM.jpeg",1280,960,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM-1280x845.jpeg",1280,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM-1024x768.jpeg",1024,768,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM-720x475.jpeg",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.20.54-AM.jpeg",1280,960,false]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/giovannamorales\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/egresados\/\" rel=\"category tag\">Egresados<\/a>","tag_info":"Egresados","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/24971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=24971"}],"version-history":[{"count":2,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/24971\/revisions"}],"predecessor-version":[{"id":24978,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/24971\/revisions\/24978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/24975"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=24971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=24971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=24971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}