{"id":22713,"date":"2026-01-31T13:11:18","date_gmt":"2026-01-31T19:11:18","guid":{"rendered":"https:\/\/wp.uaslp.mx\/noticias\/?p=22713"},"modified":"2026-01-31T13:20:30","modified_gmt":"2026-01-31T19:20:30","slug":"egresada-de-la-uaslp-comparte-una-vision-innovadora-del-derecho-y-su-ejercicio-profesional","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/orgullouaslp\/egresada-de-la-uaslp-comparte-una-vision-innovadora-del-derecho-y-su-ejercicio-profesional\/","title":{"rendered":"Egresada de la UASLP comparte una visi\u00f3n innovadora del Derecho y su ejercicio profesional"},"content":{"rendered":"\n<p>La Licenciatura en Derecho ofrece hoy un campo profesional amplio y en constante transformaci\u00f3n, que va m\u00e1s all\u00e1 del ejercicio tradicional en juzgados o despachos, y abre oportunidades en \u00e1reas estrat\u00e9gicas como la tecnolog\u00eda, la gesti\u00f3n del conocimiento y la inteligencia artificial. As\u00ed lo expuso la egresada de la <a href=\"https:\/\/www.derecho.uaslp.mx\/\">Facultad de Derecho de la Universidad Aut\u00f3noma de San Luis Potos\u00ed<\/a> (UASLP), Mar\u00eda Concepci\u00f3n Stahl Garza, cuya trayectoria internacional da cuenta de los alcances contempor\u00e1neos de esta disciplina.<\/p>\n\n\n\n<p>En entrevista, la egresada comparti\u00f3 que uno de los principales retos para quienes estudian o desean estudiar Derecho es ampliar su perspectiva sobre las m\u00faltiples posibilidades profesionales que ofrece la carrera. \u201cMuchas veces pensamos que Derecho solamente es derecho civil o penal, o que vamos a trabajar en el sector p\u00fablico. Creo que hay demasiado campo y demasiadas opciones; los invitar\u00eda a que investiguen un poquito m\u00e1s qu\u00e9 es lo que realmente les llama la atenci\u00f3n\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Stahl Garza expres\u00f3 su emoci\u00f3n por regresar a la instituci\u00f3n que marc\u00f3 el inicio de su camino profesional. \u201cEs un gusto enorme estar aqu\u00ed de regreso en la casa que me form\u00f3, la Universidad Aut\u00f3noma de San Luis Potos\u00ed. Me emociona much\u00edsimo poder compartir un poco de mi historia y de c\u00f3mo esta universidad fue el punto de partida para todo lo que he logrado\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Relat\u00f3 que su decisi\u00f3n de estudiar Derecho no fue inmediata, ya que inicialmente consider\u00f3 la carrera de Relaciones Internacionales. Sin embargo, el acompa\u00f1amiento familiar y la orientaci\u00f3n recibida por parte del entonces director de la Facultad de Derecho, maestro Fernando S\u00e1nchez L\u00e1rraga, fueron determinantes. \u201cFue \u00e9l quien me abri\u00f3 un panorama mucho m\u00e1s amplio sobre lo que pod\u00eda ser el Derecho y logr\u00f3 convencerme. Conforme fui avanzando en la carrera, me fui enamorando de la profesi\u00f3n\u201d, comparti\u00f3.<\/p>\n\n\n\n<p>La egresada record\u00f3 tambi\u00e9n la influencia de su experiencia acad\u00e9mica internacional, particularmente durante su intercambio en la Universidad de Nantes, en Francia, donde confirm\u00f3 su vocaci\u00f3n. Asimismo, destac\u00f3 a docentes que marcaron su formaci\u00f3n, entre ellos Salvador \u00c1vila Lama, Germ\u00e1n Pedroza, Daniel Medina y Manuela C\u00e1zares, cuyas ense\u00f1anzas consider\u00f3 fundamentales en su desarrollo profesional.<\/p>\n\n\n\n<p>Perteneciente a la generaci\u00f3n 2011-2016, Mar\u00eda Concepci\u00f3n Stahl Garza obtuvo el promedio m\u00e1s alto, lo que le permiti\u00f3 integrarse como asociada al despacho Candia Z\u00fa\u00f1iga Abogados. Posteriormente, realiz\u00f3 una maestr\u00eda en Derecho Corporativo y de la Empresa en la Universidad de la Sorbona, en Par\u00eds, donde adem\u00e1s trabaj\u00f3 en la firma internacional CMS, experiencia que la introdujo al \u00e1mbito del Knowledge Management.<\/p>\n\n\n\n<p>A su regreso a M\u00e9xico, se incorpor\u00f3 como docente en la Facultad de Derecho de la UASLP, para impartir la materia de Derecho Internacional Privado, adem\u00e1s de ofrecer conferencias sobre propiedad intelectual. Actualmente, se desempe\u00f1a como gerente de Knowledge Management en Baker McKenzie para las cinco oficinas de la firma en el pa\u00eds, y como Chief Artificial Intelligence Officer, adem\u00e1s de ser miembro de la Academia de Ciberseguridad y Derecho Digital en la Ciudad de M\u00e9xico y estar nominada a un premio global en la categor\u00eda Legal Tech.<\/p>\n\n\n\n<p>Sobre la relevancia de la transformaci\u00f3n digital en el \u00e1mbito jur\u00eddico, subray\u00f3 que la inteligencia artificial ya forma parte del ejercicio cotidiano del Derecho. \u201cLa tecnolog\u00eda nos ayuda a ser m\u00e1s eficientes. Una buena gesti\u00f3n de la informaci\u00f3n y un acceso adecuado al conocimiento se logra con el apoyo de herramientas tecnol\u00f3gicas, lo que hoy conocemos como Legal Tech\u201d, explic\u00f3.<\/p>\n\n\n\n<p>Finalmente, dirigi\u00f3 un mensaje a quienes se encuentran en el proceso de elegir una carrera profesional, invit\u00e1ndolos a mirar m\u00e1s all\u00e1 de los esquemas tradicionales. \u201cCreo que el Derecho tiene muchas vertientes y escenarios que quiz\u00e1 no imaginamos al inicio. Vale la pena explorar, informarse y atreverse a ver m\u00e1s all\u00e1\u201d, concluy\u00f3.<\/p>\n\n\n\n<p><em>Paola Mu\u00f1oz&nbsp;<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Licenciatura en Derecho ofrece hoy un campo profesional amplio y en constante transformaci\u00f3n, que&#8230;<\/p>\n","protected":false},"author":12,"featured_media":22717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[11],"tags":[3314],"class_list":["post-22713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orgullouaslp","tag-derechouaslp"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11.png",1800,1200,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11-150x150.png",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11-1024x683.png",1024,683,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11-768x512.png",640,427,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11.png",1800,1200,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11-1536x1024.png",1536,1024,true],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11.png",1800,1200,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11-1280x845.png",1280,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11-1024x683.png",1024,683,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11-720x475.png",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2026\/01\/Diseno-sin-titulo-11-1320x880.png",1320,880,true]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/giovannamorales\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/orgullouaslp\/\" rel=\"category tag\">Orgullo UASLP<\/a>","tag_info":"Orgullo UASLP","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/22713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=22713"}],"version-history":[{"count":3,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/22713\/revisions"}],"predecessor-version":[{"id":22721,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/22713\/revisions\/22721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/22717"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=22713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=22713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=22713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}