{"id":19171,"date":"2025-05-02T13:23:25","date_gmt":"2025-05-02T19:23:25","guid":{"rendered":"https:\/\/wp.uaslp.mx\/noticias\/?p=19171"},"modified":"2025-05-02T13:23:26","modified_gmt":"2025-05-02T19:23:26","slug":"uaslp-celebra-200-egresados-del-doctorado-en-ingenieria-y-ciencia-de-materiales","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/academica\/uaslp-celebra-200-egresados-del-doctorado-en-ingenieria-y-ciencia-de-materiales\/","title":{"rendered":"UASLP celebra 200 egresados del Doctorado en Ingenier\u00eda y Ciencia de Materiales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Para conmemorar a los 200 egresados del <a href=\"https:\/\/sites.google.com\/view\/docmateriales\">Doctorado Institucional en Ingenier\u00eda y Ciencia de Materiales<\/a> (DICIM), la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) celebr\u00f3 una emotiva ceremonia que destac\u00f3 los inicios y la trascendencia de este posgrado en el \u00e1mbito internacional, acad\u00e9mico y social, a trav\u00e9s de su vinculaci\u00f3n con la industria y la ense\u00f1anza. El evento se llev\u00f3 a cabo en el Auditorio del Centro de Emprendimiento e Innovaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje a la comunidad docente y estudiantil, el doctor Alejandro Javier Zerme\u00f1o Guerra reiter\u00f3 que, m\u00e1s all\u00e1 de una conmemoraci\u00f3n, se trat\u00f3 de una festividad del conocimiento, la constancia y el impacto que genera la ciencia cuando se construye colectivamente. Subray\u00f3 que la naturaleza interdisciplinaria del doctorado ha sido clave, as\u00ed como la valiosa intervenci\u00f3n de los colaboradores desde el inicio del programa, quienes impulsaron la apertura de un doctorado sin depender de una maestr\u00eda, siempre que los aspirantes provinieran de \u00e1reas afines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos hablando de 19 a\u00f1os de existencia del Doctorado, un promedio mayor a 10 egresados por a\u00f1o. Es f\u00e1cil decirlo, pero para lograrlo se necesit\u00f3 del trabajo colaborativo interinstitucional e interdisciplinario, adem\u00e1s de profesores de diversas \u00e1reas, lo que permiti\u00f3 ofrecer el programa y recibir alumnos de otras partes del mundo y de M\u00e9xico\u201d, apunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, puntualiz\u00f3 que los logros obtenidos son el resultado del trabajo de generaciones anteriores, tanto de maestros como de alumnos, y que representan una valiosa ense\u00f1anza para la educaci\u00f3n superior, siendo un \u00e9xito institucional el egreso de 200 estudiantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la coordinadora del DICIM, Dra. Mildred Quintana Ruiz, reconoci\u00f3 que el posgrado ha facilitado la construcci\u00f3n de diversos puentes con instituciones como la Universidad Tecnol\u00f3gica de Wuhan, en China; dependencias estatales como el IPICyT; as\u00ed como con instituciones nacionales y extranjeras, fortaleciendo la vinculaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un doctorado que no cuenta con una maestr\u00eda como la mayor\u00eda de los programas; es un posgrado totalmente inter y multidisciplinario, conformado por estudiantes de m\u00e1s de 10 pa\u00edses. La mayor\u00eda proviene de China, pero tambi\u00e9n de Sudam\u00e9rica, Europa, Estados Unidos y de distintos estados de la Rep\u00fablica Mexicana\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los m\u00e1s de 200 egresados del Doctorado Institucional en Ingenier\u00eda y Ciencia de Materiales actualmente se desempe\u00f1an, en su mayor\u00eda, en centros de investigaci\u00f3n e industrias en China, Europa y otras regiones del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ceremonia cont\u00f3, adem\u00e1s, con la presencia del secretario de Investigaci\u00f3n y Posgrado, Dr. Amaury de Jes\u00fas Pozos Guill\u00e9n; la Dra. Rosalba Medina Rivera, directora del Consejo Potosino de Ciencia y Tecnolog\u00eda; y el Dr. Jos\u00e9 Luis Mor\u00e1n L\u00f3pez, director de la Divisi\u00f3n de Materiales Avanzados del IPICyT.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Noelia Mart\u00ednez<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"19172\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.58.jpeg\" alt=\"\" class=\"wp-image-19172\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.58.jpeg 1600w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.58-1024x768.jpeg 1024w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.58-768x576.jpeg 768w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.58-1536x1152.jpeg 1536w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.58-1320x990.jpeg 1320w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Para conmemorar a los 200 egresados del Doctorado Institucional en Ingenier\u00eda y Ciencia de Materiales&#8230;<\/p>\n","protected":false},"author":12,"featured_media":19173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[2,11],"tags":[416],"class_list":["post-19171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academica","category-orgullouaslp","tag-ingenieria"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48.jpeg",1600,1200,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48-150x150.jpeg",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48-1024x768.jpeg",1024,768,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48-768x576.jpeg",640,480,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48.jpeg",1600,1200,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48-1536x1152.jpeg",1536,1152,true],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48.jpeg",1600,1200,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48-1280x845.jpeg",1280,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48-1024x768.jpeg",1024,768,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48-720x475.jpeg",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2025\/05\/WhatsApp-Image-2025-05-02-at-13.13.48-1320x990.jpeg",1320,990,true]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/giovannamorales\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/academica\/\" rel=\"category tag\">Acad\u00e9mica<\/a> <a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/orgullouaslp\/\" rel=\"category tag\">Orgullo UASLP<\/a>","tag_info":"Orgullo UASLP","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/19171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=19171"}],"version-history":[{"count":1,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/19171\/revisions"}],"predecessor-version":[{"id":19174,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/19171\/revisions\/19174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/19173"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=19171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=19171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=19171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}