{"id":11230,"date":"2023-10-12T15:44:51","date_gmt":"2023-10-12T20:44:51","guid":{"rendered":"http:\/\/wp.uaslp.mx\/noticias\/?p=11230"},"modified":"2023-10-12T15:44:52","modified_gmt":"2023-10-12T20:44:52","slug":"encuentro-anuies-tic-uaslp-2023-plataforma-para-el-aprendizaje-e-intercambio-de-conocimientos","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/academica\/encuentro-anuies-tic-uaslp-2023-plataforma-para-el-aprendizaje-e-intercambio-de-conocimientos\/","title":{"rendered":"Encuentro ANUIES-TIC UASLP 2023, plataforma para el aprendizaje e intercambio de conocimientos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante este jueves 12 y viernes 13 de octubre, la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) ser\u00e1 sede de las conferencias magistrales presenciales del <a href=\"https:\/\/encuentro-tic.anuies.mx\" target=\"_blank\" rel=\"noopener\" title=\"\">Encuentro ANUIES-TIC UASLP 2023<\/a> &#8220;La transformaci\u00f3n digital de la educaci\u00f3n superior para una nueva sociedad&#8221;, con sede en instalaciones del Centro Cultural Universitario Bicentenario (CC200).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa de esta actividad incluye 19 conferencias, paneles de expertos con m\u00e1s de 50 ponentes reconocidos a nivel nacional e internacional, 11 talleres especializados, as\u00ed como una exposici\u00f3n de la industria TIC con 27 empresas, espacios para sesiones especiales con orientaci\u00f3n sobre programas formativos y complementarios en el \u00e1mbito de las TIC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/www.youtube.com\/watch?v=GA0tBN7CmZ4\" target=\"_blank\" rel=\"noopener\" title=\"\">ceremonia de apertura<\/a> estuvo a cargo de la Dra. <a href=\"https:\/\/www.facebook.com\/CarmentaE\" target=\"_blank\" rel=\"noopener\" title=\"\">Carmen Enedina Rodr\u00edguez Armenta<\/a>, directora general de Educaci\u00f3n Superior Universitaria e Intercultural de la Secretaria de Educaci\u00f3n P\u00fablica del Gobierno Federal; el rector de la Universidad Aut\u00f3noma de San Luis Potos\u00ed, Dr. Alejandro Javier Zerme\u00f1o Guerra; el secretario general ejecutivo de la Asociaci\u00f3n Nacional de Universidades e Instituciones de Educaci\u00f3n Superior (<a href=\"https:\/\/www.facebook.com\/anuies\" target=\"_blank\" rel=\"noopener\" title=\"\">ANUIES<\/a>) Dr. Luis Armando Gonz\u00e1lez Plascencia; y el Dr. Arturo Cherbowsky Lask, director de <a href=\"https:\/\/www.facebook.com\/santanderuniversidades\" target=\"_blank\" rel=\"noopener\" title=\"\">Santander Universidades<\/a>, Universia M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje inaugural, la Dra. Carmen Enedina Rodr\u00edguez Armenta, manifest\u00f3 que desde la Secretaria de Educaci\u00f3n P\u00fablica, resulta fundamental colocar la importancia de las tecnolog\u00edas de la informaci\u00f3n, sobre todo, de la educaci\u00f3n superior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconoci\u00f3 que gracias a las tecnolog\u00edas de la informaci\u00f3n, en este per\u00edodo post pand\u00e9mico se pudo reconocer que los estudiantes no se fueron, estuvieron en un espacio donde los profesores abrieron sus hogares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y se advirti\u00f3 que el mayor obst\u00e1culo fue la conectividad y el ancho de banda, tanto de estudiantes de educacion p\u00fablica, como de educaci\u00f3n privada. &#8220;En este sentido, las tecnolog\u00edas de la informaci\u00f3n tienen mucho qu\u00e9 decir, por ello, es importante que aprovechemos y potencialicemos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, el Dr. Alejandro Zerme\u00f1o Guerra, asegur\u00f3 que este evento, de la mano con la ANUIES y la Secretaria de Educaci\u00f3n P\u00fablica, arribar\u00e1 a una mejor forma de educar a los estudiantes, ya que indiscutiblemente despu\u00e9s de la pandemia el panorama cambi\u00f3, y adem\u00e1s las condiciones de preparaci\u00f3n de los j\u00f3venes permitieron adentrarse a las nuevas tecnolog\u00edas e ingreso a la inteligencia artificial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esto se aprovech\u00f3 para tener un crecimiento vertiginoso en el que los j\u00f3venes encontrar\u00e1n un plan de desarrollo con m\u00e1s eficacia en los conocimientos adquiridos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el Dr. Luis Armando Gonz\u00e1lez Plascencia, secretario general de la ANUIES, aplaudi\u00f3 que el Encuentro se enmarque en la conmemoraci\u00f3n de los 100 a\u00f1os de autonom\u00eda de la UASLP, tributo a la independencia y compromiso de las Universidades por la mejora continua y la b\u00fasqueda constante del conocimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Subray\u00f3 que este Encuentro no solo representa una oportunidad para el intercambio de conocimientos y buenas pr\u00e1cticas, tambi\u00e9n simboliza un momento importante para la Asociaci\u00f3n en la evoluci\u00f3n de la educaci\u00f3n superior en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el Encuentro <a href=\"https:\/\/www.facebook.com\/anuiestic\" target=\"_blank\" rel=\"noopener\" title=\"\">ANUIES-TIC<\/a> se explorar\u00e1n temas cruciales que marquen la pauta del futuro de la educaci\u00f3n superior del pa\u00eds, el concepto de Sociedad 5.0 que aborda la convergencia de la Sociedad y la tecnolog\u00eda, la inteligencia artificial, entre otros temas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento tambi\u00e9n estuvo presente la Mtra. Gloria Edith Palacios, directora de Educaci\u00f3n media superior y superior del Gobierno del Estado; y la Dra. Rosalba Medina Rivera, directora general del Consejo Potosino de Ciencia y Tecnolog\u00eda (COPOCYT).<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" data-id=\"11232\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-1.jpeg\" alt=\"\" class=\"wp-image-11232\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-1.jpeg 1600w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-1-1024x682.jpeg 1024w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-1-768x512.jpeg 768w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-1-1536x1023.jpeg 1536w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-1-1320x879.jpeg 1320w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-4.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" data-id=\"11233\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-4.jpeg\" alt=\"\" class=\"wp-image-11233\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-4.jpeg 1600w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-4-1024x682.jpeg 1024w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-4-768x512.jpeg 768w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-4-1536x1023.jpeg 1536w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-4-1320x879.jpeg 1320w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Noelia Mart\u00ednez \/ MR<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante este jueves 12 y viernes 13 de octubre, la Universidad Aut\u00f3noma de San Luis&#8230;<\/p>\n","protected":false},"author":14,"featured_media":11231,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[2,782],"tags":[45,1607,706],"class_list":["post-11230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academica","category-uaslp","tag-anuies","tag-tic","tag-uaslp"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3.jpeg",1600,1066,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3-150x150.jpeg",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3-1024x682.jpeg",1024,682,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3-768x512.jpeg",640,427,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3.jpeg",1600,1066,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3-1536x1023.jpeg",1536,1023,true],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3.jpeg",1600,1066,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3-1280x845.jpeg",1280,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3-1024x682.jpeg",1024,682,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3-720x475.jpeg",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/10\/Encuentro-ANUIES-TIC-UASLP-2023-3-1320x879.jpeg",1320,879,true]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/taliacorpus\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/academica\/\" rel=\"category tag\">Acad\u00e9mica<\/a> <a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/uaslp\/\" rel=\"category tag\">UASLP<\/a>","tag_info":"UASLP","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/11230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=11230"}],"version-history":[{"count":1,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/11230\/revisions"}],"predecessor-version":[{"id":11234,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/11230\/revisions\/11234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/11231"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=11230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=11230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=11230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}