{"id":10958,"date":"2023-09-25T14:37:48","date_gmt":"2023-09-25T19:37:48","guid":{"rendered":"http:\/\/wp.uaslp.mx\/noticias\/?p=10958"},"modified":"2023-09-25T14:39:20","modified_gmt":"2023-09-25T19:39:20","slug":"con-talleres-y-exhibicion-de-peliculas-el-6to-festival-de-cine-uaslp-se-hara-presente-en-ciudad-valles","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/arteycultura\/con-talleres-y-exhibicion-de-peliculas-el-6to-festival-de-cine-uaslp-se-hara-presente-en-ciudad-valles\/","title":{"rendered":"Con talleres y exhibici\u00f3n de pel\u00edculas, el 6to Festival de Cine UASLP se har\u00e1 presente en Ciudad Valles"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) a trav\u00e9s de la <a href=\"https:\/\/www.facebook.com\/profile.php?id=100068619993470\" target=\"_blank\" rel=\"noopener\" title=\"\">Secretar\u00eda de Difusi\u00f3n Cultural<\/a>, hace una atenta invitaci\u00f3n a la comunidad universitaria de la <a href=\"https:\/\/www.facebook.com\/uaslp.zona.huasteca\" target=\"_blank\" rel=\"noopener\" title=\"\">Facultad de Estudios Profesionales Zona Huasteca<\/a> (FEPZH) as\u00ed como a la sociedad en general, para que sean part\u00edcipes de los talleres que se estar\u00e1n impartiendo as\u00ed como de la exhibici\u00f3n de excelentes filmes, dentro del <a href=\"https:\/\/www.facebook.com\/festivaldecineuaslp\" target=\"_blank\" rel=\"noopener\" title=\"\">6to. Festival de Cine UASLP.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del 03 al 05 de octubre de 2023, se impartir\u00e1 el \u201cTaller de Doblaje\u201d, a cargo de la reconocida Elsa Covi\u00e1n, cuya sede ser\u00e1 la Sala A del Edificio de Derecho de la FEPZH. Con horario de 16:00 a 19:00 horas, y de costo de 250 pesos. El cupo es limitado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los d\u00edas 03 y 04 de octubre de 2023, \u00c1ngela Salgado otorgar\u00e1 el \u201cTaller Arte y T\u00e9cnica, Maquillaje para Cine\u201d. Mismo que ser\u00e1 impartido en la Sala B del Edificio de Derecho, en la FEPZH. El taller se realizar\u00e1 de 16:00 a 19:00 horas; el costo es de 250 pesos, cupo limitado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera, los d\u00edas 03 y 04 de octubre de 2023, Joaqu\u00edn Loustanau impartir\u00e1 el \u201cTaller de Principios B\u00e1sicos de Cine Fotograf\u00eda\u201d, en un horario de 16:00 a 19:00 horas. La sede ser\u00e1 la Sala G del Edificio de Arquitectura en la Facultad de Estudios Profesionales Zona Huasteca; el costo es de 250 pesos, tambi\u00e9n con cupo limitado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de la exhibici\u00f3n de pel\u00edculas, el martes 03 de octubre se presentar\u00e1 \u201c\u00bfC\u00f3mo matar a mam\u00e1?\u201d, pel\u00edcula que cuenta con las actuaciones de Ximena Sari\u00f1ana y Blanca Guerra; estar\u00e1 presente su director Jos\u00e9 Ram\u00f3n Ch\u00e1vez, en punto de las 19:30 horas, teniendo como escenario la Plaza Principal de Ciudad Valles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el mi\u00e9rcoles 04 de octubre a las 19:30 horas, en la Plaza Principal de Ciudad Valles, se presentar\u00e1 el cortometraje \u201cLow\u201d de Joaqu\u00edn Loustaunau. Y a las 19:45 horas el documental, \u201cLeonora despu\u00e9s del pincel\u201d, de Alan David Cabrera. El cortometraje y el documental contar\u00e1n con la asistencia de sus directores, quienes conversar\u00e1n con el p\u00fablico. El jueves 05 de octubre, en punto de las 19:30 horas, en la Plaza Principal de Cd. Valles, ser\u00e1 exhibida \u201cFinlandia\u201d, nominada a mejor vestuario y mejor pel\u00edcula en los Arieles 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mayores informes e inscripciones los interesados deben visitar la p\u00e1gina: <a href=\"https:\/\/www.uaslp.mx\/DifusionCultural\/Paginas\/6FestivaldeCine\/5145#gsc.tab=0\" target=\"_blank\" rel=\"noopener\" title=\"\">https:\/\/www.uaslp.mx\/DifusionCultural\/Paginas\/6FestivaldeCine\/5145#gsc.tab=0<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/380889605_775922574544262_8294952114223635691_n.jpg\" alt=\"\" class=\"wp-image-10959\" width=\"840\" height=\"840\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/380889605_775922574544262_8294952114223635691_n.jpg 1000w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/380889605_775922574544262_8294952114223635691_n-150x150.jpg 150w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/380889605_775922574544262_8294952114223635691_n-768x768.jpg 768w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Am\u00e9rica Reyes \/ MR<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) a trav\u00e9s de la Secretar\u00eda de Difusi\u00f3n&#8230;<\/p>\n","protected":false},"author":14,"featured_media":10895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[3,782],"tags":[146,332,337,706],"class_list":["post-10958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arteycultura","category-uaslp","tag-cine","tag-fepzh","tag-festival","tag-uaslp"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo.png",1800,1200,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo-150x150.png",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo-1024x683.png",1024,683,true],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo-768x512.png",640,427,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo.png",1800,1200,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo-1536x1024.png",1536,1024,true],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo.png",1800,1200,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo-1280x845.png",1280,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo-1024x683.png",1024,683,true],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo-720x475.png",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/Disen\u0303o-sin-ti\u0301tulo-1320x880.png",1320,880,true]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/taliacorpus\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/arteycultura\/\" rel=\"category tag\">Arte y cultura<\/a> <a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/uaslp\/\" rel=\"category tag\">UASLP<\/a>","tag_info":"UASLP","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/10958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=10958"}],"version-history":[{"count":2,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/10958\/revisions"}],"predecessor-version":[{"id":10961,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/10958\/revisions\/10961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/10895"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=10958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=10958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=10958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}