{"id":10768,"date":"2023-09-13T16:17:33","date_gmt":"2023-09-13T21:17:33","guid":{"rendered":"http:\/\/wp.uaslp.mx\/noticias\/?p=10768"},"modified":"2023-09-13T16:17:34","modified_gmt":"2023-09-13T21:17:34","slug":"interesantes-talleres-seran-impartidos-en-el-6to-festival-de-cine-uaslp","status":"publish","type":"post","link":"https:\/\/wp.uaslp.mx\/noticias\/arteycultura\/interesantes-talleres-seran-impartidos-en-el-6to-festival-de-cine-uaslp\/","title":{"rendered":"Interesantes talleres ser\u00e1n impartidos en el 6to. Festival de Cine UASLP"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Como parte de las actividades del 6to. <a href=\"https:\/\/www.uaslp.mx\/DifusionCultural\/Paginas\/Festivales-y-concursos\/812#gsc.tab=0\" target=\"_blank\" rel=\"noopener\" title=\"\">Festival de Cine<\/a>, organizado por la <a href=\"https:\/\/www.uaslp.mx\/DifusionCultural#gsc.tab=0\" target=\"_blank\" rel=\"noopener\" title=\"\">Secretar\u00eda de Difusi\u00f3n Cultural <\/a>de la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP), se invita a las y los interesados en participar en los talleres disponibles tanto en \u00e1reas audiovisuales como cinematogr\u00e1ficas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal es el caso del \u201cTaller de Guionismo\u201d que ser\u00e1 impartido del 03 al 05 de octubre de 2023, por Luis Fernando Fr\u00edas, director de la pel\u00edcula \u201cYa no estoy aqu\u00ed\u201d, cuyo alcance lleg\u00f3 hasta los premios Oscar el a\u00f1o pasado, el cupo se encuentra agotado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera, se contar\u00e1 con la presencia de Juan Jos\u00e9 Medina, de \u201cEl Taller del Chucho\u201d, de Guillermo Del Toro, quien compartir\u00e1 sus conocimientos del 02 al 04 de octubre de 2023 en el \u201cTaller de Animaci\u00f3n\u201d, del cual quedan pocos lugares. Adem\u00e1s, impartir\u00e1 una charla para todo p\u00fablico el mi\u00e9rcoles 04 de octubre de 2023, a las 16:00 horas en la Facultad de Ciencias de la Comunicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se impartir\u00e1n los talleres de \u201cPrincipio del sonido directo para el cine\u201d, del 02 al 04 de octubre de 2023, con Alfredo Loaeza; \u201cCreaci\u00f3n Argumental\u201d, con Luc\u00eda Carreras, del 04 al 06 de octubre de 2023; \u201cInvestigaci\u00f3n para Cine Documental\u201d, del 03 al 05 de octubre de 2023, con Cristina Soto; y \u201cTaller de Doblaje\u201d, del 02 al 04 de octubre de 2023, con Carlos Segundo, el cual se encuentra agotado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se hace una especial menci\u00f3n a la comunidad de Ciudad Valles y Matehuala, para que est\u00e9n atentos a los talleres que estar\u00e1n disponibles en aquellas entidades acad\u00e9micas universitarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El costo de los talleres es simb\u00f3lico, dada la calidad de los expositores, y tiene un costo de 250 pesos, con el cual se les otorga un kit de bienvenida a las y los participantes. Cabe mencionar que los talleres se impartir\u00e1n en diferentes sedes, por lo que se requiere revisar la informaci\u00f3n a trav\u00e9s de la p\u00e1gina de Facebook <a href=\"https:\/\/www.facebook.com\/festivaldecineuaslp\" target=\"_blank\" rel=\"noopener\" title=\"\">Festival de Cine UASLP<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso para inscripci\u00f3n a cualquiera de los talleres se encuentra detallada en el link: <a href=\"https:\/\/www.uaslp.mx\/DifusionCultural\/Paginas\/6FestivaldeCine\/5130?fbclid=IwAR1N_cWgQidnjvEbzHxhNTW1mHvBRv-b89NA8EFJr_Z1Ub91J5DUN4jvleQ#ggsc.tab=0\" target=\"_blank\" rel=\"noopener\" title=\"\">https:\/\/www.uaslp.mx\/DifusionCultural\/Paginas\/6FestivaldeCine\/5130?fbclid=IwAR1N_cWgQidnjvEbzHxhNTW1mHvBRv-b89NA8EFJr_Z1Ub91J5DUN4jvleQ#ggsc.tab=0<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/373632057_759943472808839_8129133779644636023_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-id=\"10771\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/373632057_759943472808839_8129133779644636023_n.jpg\" alt=\"\" class=\"wp-image-10771\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/373632057_759943472808839_8129133779644636023_n.jpg 1000w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/373632057_759943472808839_8129133779644636023_n-150x150.jpg 150w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/373632057_759943472808839_8129133779644636023_n-768x768.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/374372083_759943482808838_819797419349427936_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-id=\"10770\" src=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/374372083_759943482808838_819797419349427936_n.jpg\" alt=\"\" class=\"wp-image-10770\" srcset=\"https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/374372083_759943482808838_819797419349427936_n.jpg 1000w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/374372083_759943482808838_819797419349427936_n-150x150.jpg 150w, https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/374372083_759943482808838_819797419349427936_n-768x768.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Am\u00e9rica Reyes \/ MR<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de las actividades del 6to. Festival de Cine, organizado por la Secretar\u00eda de&#8230;<\/p>\n","protected":false},"author":14,"featured_media":10769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[3],"tags":[146,337,706],"class_list":["post-10768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arteycultura","tag-cine","tag-festival","tag-uaslp"],"featured_image_urls":{"full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP.jpeg",1000,1000,false],"thumbnail":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP-150x150.jpeg",150,150,true],"medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP.jpeg",1000,1000,false],"medium_large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP-768x768.jpeg",640,640,true],"large":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP.jpeg",1000,1000,false],"1536x1536":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP.jpeg",1000,1000,false],"2048x2048":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP.jpeg",1000,1000,false],"newsever-slider-full":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP-1000x845.jpeg",1000,845,true],"newsever-featured":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP.jpeg",1000,1000,false],"newsever-medium":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP-720x475.jpeg",720,475,true],"mailpoet_newsletter_max":["https:\/\/wp.uaslp.mx\/noticias\/wp-content\/uploads\/sites\/5\/2023\/09\/6o.-Festival-de-Cine-de-la-UASLP.jpeg",1000,1000,false]},"author_info":{"display_name":"Prensa y difusi\u00f3n","author_link":"https:\/\/wp.uaslp.mx\/noticias\/author\/taliacorpus\/"},"category_info":"<a href=\"https:\/\/wp.uaslp.mx\/noticias\/category\/arteycultura\/\" rel=\"category tag\">Arte y cultura<\/a>","tag_info":"Arte y cultura","comment_count":"0","_links":{"self":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/10768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/comments?post=10768"}],"version-history":[{"count":1,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/10768\/revisions"}],"predecessor-version":[{"id":10772,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/posts\/10768\/revisions\/10772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media\/10769"}],"wp:attachment":[{"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/media?parent=10768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/categories?post=10768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.uaslp.mx\/noticias\/wp-json\/wp\/v2\/tags?post=10768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}